{"id":10262,"date":"2022-12-07T14:53:13","date_gmt":"2022-12-07T12:53:13","guid":{"rendered":"http:\/\/comdiflex.com\/criterios-esg\/"},"modified":"2022-12-12T12:33:54","modified_gmt":"2022-12-12T10:33:54","slug":"criteres-esg","status":"publish","type":"post","link":"https:\/\/comdiflex.com\/fr\/criteres-esg\/","title":{"rendered":"CRIT\u00c8RES ESG"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1012.96px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" style=\"transform:translate3d(0,0,0);\"><h2 style=\"text-align: center;\"><strong>RAPPORT SUR LES CRIT\u00c8RES ESG DANS LA SOCI\u00c9T\u00c9<br \/>\nGRUPO INDUSTRIAL KEMPCHEN COMDIFLEX, SA<\/strong><\/h2>\n<p style=\"text-align: center;\">(2022)<\/p>\n<p>Tant dans sa direction que dans son groupe d&rsquo;actionnaires, GIKC, SA est enti\u00e8rement ax\u00e9e, au-del\u00e0 de la viabilit\u00e9 financi\u00e8re, sur la durabilit\u00e9 environnementale et la responsabilit\u00e9 du bien-\u00eatre de toutes les personnes qui travaillent et vivent autour de notre entreprise et de nos activit\u00e9s.<\/p>\n<p>L&rsquo;actionnariat de la soci\u00e9t\u00e9, 100% espagnole, est dans la m\u00eame famille depuis sa cr\u00e9ation, la famille Ruiz et Villandiego.<\/p>\n<p>Cette \u00ab\u00a0culture d&rsquo;entreprise\u00a0\u00bb, bas\u00e9e sur ce qu&rsquo;on appelle d\u00e9sormais les \u00ab\u00a0Crit\u00e8res ESG\u00a0\u00bb, constitue l&rsquo;ADN de l&rsquo;entreprise depuis sa cr\u00e9ation par ses fondateurs et premier dirigeant M. Jos\u00e9 Cruz Ruiz Zufiaur avec son \u00e9pouse M\u00aa del Carmen Villandiego.<\/p>\n<p>Aujourd&rsquo;hui, plus de 50 ans plus tard, ces crit\u00e8res continuent d&rsquo;\u00eatre \u00e0 la base du management et du quotidien de tous les travailleurs. Nous prenons soin les uns des autres, prenons soin de notre environnement, de nos fournisseurs, de nos clients et aussi de nos concurrents car le monde est commun et nous pouvons toujours avoir besoin les uns des autres.<\/p>\n<p>Concernant les crit\u00e8res ESG, nous commencerons par les mesures que nous menons pour nous conformer \u00e0 la premi\u00e8re lettre.<\/p>\n<p style=\"text-align: center;\"><strong><u>\u00ab\u00a0E\u00a0\u00bb pour \u00ab\u00a0environnemental\u00a0\u00bb<\/u><\/strong><\/p>\n<p>Notre engagement envers l&rsquo;environnement.<\/p>\n<p>Notre objectif n&rsquo;est pas seulement de minimiser les \u00e9ventuels effets n\u00e9gatifs de notre activit\u00e9, mais aussi d&rsquo;entreprendre des actions qui g\u00e9n\u00e8rent un impact positif direct. Dans ce domaine, nous adoptons toutes les mesures, des mesures l\u00e9gales jusqu&rsquo;au-del\u00e0 dans notre conscience la plus intime.<\/p>\n<p>Les mesures de responsabilit\u00e9 environnementale que nous mettons en place dans notre entreprise sont les suivantes :<\/p>\n<ul>\n<li>Nous utilisons des palettes et des caisses en bois recyclables et r\u00e9utilisables, ce qui se traduit par une r\u00e9duction de plus de <strong>20% <\/strong>par an de la consommation de bois.<\/li>\n<li>Dans la mesure du possible, nous essayons de ne pas utiliser de plastiques, mousses ou polym\u00e8res non recyclables dans nos emballages, ayant r\u00e9duit l&rsquo;achat de d\u00e9riv\u00e9s plastiques de plus de <strong>80% au cours des 3 derni\u00e8res ann\u00e9es.<\/strong><\/li>\n<li>Nous avons interdit en interne l&rsquo;utilisation des a\u00e9rosols dans toutes nos installations depuis 2016, r\u00e9duisant sa consommation \u00e0 pratiquement <strong>0, <\/strong>et dans les cas essentiels, nous g\u00e9rons le recyclage de ses contenants avec la soci\u00e9t\u00e9 agr\u00e9\u00e9e <strong>BIDASOA ECO GESTION. <\/strong>Nos dossiers montrent que cette gestion responsable avec <strong>BIDASOA ECO GESTION <\/strong>nous a co\u00fbt\u00e9 3 713,84 \u20ac ces derni\u00e8res ann\u00e9es, mais nous avons ainsi r\u00e9alis\u00e9 un recyclage complet des contenants a\u00e9rosols.<\/li>\n<li>la philosophie z\u00e9ro papier depuis <strong>2019 . <\/strong>Le papier utilis\u00e9 dans les bureaux doit \u00eatre recycl\u00e9, nous avons donc r\u00e9duit sa consommation de <strong>6 000 \u20ac \u00e0 <\/strong>environ 1 200 \u20ac, avec 100 % de papier d&rsquo;origine recycl\u00e9e.<\/li>\n<li>Nous avons toujours recycl\u00e9 et depuis 2020 nous classons nos d\u00e9chets m\u00e9talliques, selon leur composition, pour maximiser le recyclage. Cela nous donne une augmentation de notre compte de r\u00e9sultat, dans le poste ferraille de plus de <strong>40%, <\/strong>en plus de nous assurer que la quasi-totalit\u00e9 de nos d\u00e9chets m\u00e9talliques est recycl\u00e9e.<\/li>\n<li>Nous essayons de nous approvisionner aupr\u00e8s d&rsquo;entreprises \u00e0 proximit\u00e9, afin de minimiser les \u00e9missions de carbone dans l&rsquo;atmosph\u00e8re.<\/li>\n<li>Nous g\u00e9rons nos d\u00e9chets de mani\u00e8re responsable, ne d\u00e9versant aucun type de d\u00e9chets dans les \u00e9gouts. Nous n&rsquo;avons pas de rapports sur la r\u00e9duction des rejets, car cela n&rsquo;a jamais \u00e9t\u00e9 fait.<\/li>\n<li>Tous les travailleurs du personnel vivent dans la zone o\u00f9 se trouvent les entrep\u00f4ts de l&rsquo;entreprise. Dans les nouvelles embauches, nous essayons toujours de s\u00e9lectionner des personnes des villes proches, pour faciliter et ainsi \u00e9viter les longs trajets. Les activit\u00e9s communautaires en dehors des installations sont r\u00e9alis\u00e9es avec des transports collectifs.<\/li>\n<li>Nos fournisseurs sont \u00e9galement alert\u00e9s sur l&rsquo;importance qu&rsquo;il faut accorder \u00e0 l&rsquo;utilisation du papier, des plastiques d&#8217;emballage et du bois recyclable.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><strong><u>Le \u00ab\u00a0S\u00a0\u00bb dans \u00ab\u00a0social\u00a0\u00bb<\/u><\/strong><\/p>\n<p>Les propri\u00e9taires actuels de Kempchen Comdiflex (fils du fondateur) sont m\u00e9decins et exigent le respect des mesures de s\u00e9curit\u00e9 au travail au-del\u00e0 de la r\u00e9glementation sur les risques professionnels.<\/p>\n<p>Ils ont transf\u00e9r\u00e9 la gestion quotidienne \u00e0 D\u00aa Arancha Guerrero, donnant encore plus d&rsquo;importance au bien-\u00eatre \u00e9motionnel qu&rsquo;au physique. S&rsquo;inqui\u00e9ter et veiller \u00e0 ce que l&rsquo;ambiance dans l&rsquo;entreprise soit vraiment affable, loin des conflits personnels ou collectifs. Des audits externes des ressources humaines ont \u00e9t\u00e9 contract\u00e9s assez fr\u00e9quemment pour conna\u00eetre l&rsquo;\u00e9tat \u00e9motionnel personnel et collectif de la main-d&rsquo;\u0153uvre.<\/p>\n<p>L&rsquo;administration et la direction sont profond\u00e9ment convaincues qu&rsquo;une main-d&rsquo;\u0153uvre heureuse se traduit par la qualit\u00e9 des produits et un excellent service client. Les deux sont des aspects cl\u00e9s dans le secteur d\u00e9j\u00e0 tr\u00e8s exigeant dans lequel nous travaillons.<\/p>\n<p>Depuis le d\u00e9but de l&rsquo;entreprise, dans les ann\u00e9es 1960, m\u00eame dans l&rsquo;Accord d&rsquo;Entreprise, il y avait une clause selon laquelle les membres de la famille des salari\u00e9s avaient et ont la priorit\u00e9 dans les nouvelles embauches, cr\u00e9ant ainsi un sentiment d&rsquo;appartenance \u00e0 l&rsquo;entreprise et de \u00ab\u00a0famille \u00a0\u00bb qui honore l&rsquo;entreprise d&rsquo;une loyaut\u00e9 et d&rsquo;un respect dignes de toute admiration. Beaucoup des travailleurs actuels de l&rsquo;entreprise sont des enfants d&rsquo;anciens travailleurs qui ont pris leur retraite \u00ab\u00a0\u00e0 la maison\u00a0\u00bb et nous avons d\u00e9j\u00e0 une troisi\u00e8me g\u00e9n\u00e9ration.<\/p>\n<p>Nous ne nous nourrissons pas de contrats temporaires. Nos travailleurs b\u00e9n\u00e9ficient ainsi de la s\u00e9curit\u00e9 et de la stabilit\u00e9 pour d\u00e9velopper leur vie personnelle sans souci.<\/p>\n<p>En plus de cela, dans le cadre de la politique de l&rsquo;entreprise, une flexibilit\u00e9 horaire est \u00e9galement pr\u00e9vue afin d&rsquo;adapter les horaires des travailleurs pour concilier leur vie familiale.<\/p>\n<p>Kempchen-Comdiflex est aussi une entreprise \u00e0 projection solidaire. Et les travailleurs en sont conscients.<\/p>\n<p>R\u00e9cemment, par exemple, au d\u00e9but du conflit russo-ukrainien, les travailleurs de l&rsquo;entreprise ont \u00e9t\u00e9 impliqu\u00e9s dans l&rsquo;achat de v\u00eatements et de nourriture \u00e0 exp\u00e9dier en Ukraine. Nous essayons que notre contribution aux probl\u00e8mes qui nous entourent ne soit pas de simples d\u00e9penses financi\u00e8res. nous le faisons ensemble.<\/p>\n<p>fondation <strong>AMIGOS SOLIDARIOS , <\/strong>qui \u0153uvre pour et pour l&rsquo;\u00e9ducation et l&rsquo;\u00e9galit\u00e9 en Ouganda.<\/p>\n<p>En ce qui concerne les politiques d&rsquo;\u00e9galit\u00e9 et de diversit\u00e9, nous n&rsquo;avons jamais eu de conflit \u00e0 cet \u00e9gard. Ils n&rsquo;auraient pas leur place dans l&rsquo;entreprise. Bien que la plupart des ouvriers des ateliers soient des hommes, il y a aussi des femmes et bien que la plupart des employ\u00e9s de bureau soient des femmes, il y a aussi des hommes. Sans surprise, l&rsquo;administrateur est un homme et le gestionnaire est une femme.<\/p>\n<p>La relation entre tous est amicale et la relation entre les gens de l&rsquo;atelier et des bureaux est constante. Nous sommes habitu\u00e9s \u00e0 travailler dans l&rsquo;urgence et cela signifie que le service commercial et l&rsquo;atelier ont besoin d&rsquo;une communication fluide sur les priorit\u00e9s, la disponibilit\u00e9 des mati\u00e8res premi\u00e8res, le transport, etc. C&rsquo;est l\u00e0 que na\u00eet l&rsquo;engagement pour l&rsquo;\u00e9galit\u00e9 et la coresponsabilit\u00e9, qui est promu par la direction.<\/p>\n<p>Ajoutez que nous avons du personnel de diff\u00e9rentes nationalit\u00e9s et qu&rsquo;il n&rsquo;y a jamais eu de conflit, m\u00eame minime. Le respect de l&rsquo;orientation sexuelle, politique ou religieuse est absolu.<\/p>\n<p>Comme indiqu\u00e9 pr\u00e9c\u00e9demment, le traitement encourag\u00e9 doit toujours \u00eatre respectueux, amical et familier, il n&rsquo;y a donc pas de conflits de ce type. La tol\u00e9rance serait nulle.<\/p>\n<p style=\"text-align: center;\"><strong><u>Le \u00ab G \u00bb pour \u00ab <\/u><\/strong><strong><u>gouvernance <\/u><\/strong><strong><u>\u00bb<\/u><\/strong><\/p>\n<p>Aujourd&rsquo;hui, Kempchen-Comdiflex est une soci\u00e9t\u00e9 anonyme et ses actions appartiennent aux h\u00e9ritiers du fondateur.<\/p>\n<p>Jos\u00e9 Cruz Ruiz Zufiaur a eu trois enfants : Jos\u00e9 Cruz Jr., Eric et I\u00f1igo. Jose Cruz et I\u00f1igo sont m\u00e9decins. Le premier est actuellement chef du service d&rsquo;odonto-stomatologie \u00e0 l&rsquo;h\u00f4pital Quir\u00f3n de San Sebasti\u00e1n et le second est responsable de la radiologie \u00e0 l&rsquo;h\u00f4pital de Jerez.<\/p>\n<p>C&rsquo;est Eric, d\u00e9c\u00e9d\u00e9 il y a quelques ann\u00e9es des suites d&rsquo;une longue maladie, qui \u00e9tait destin\u00e9 \u00e0 diriger l&rsquo;entreprise fond\u00e9e par son p\u00e8re. Il a \u00e9tudi\u00e9 pour cela \u00e0 Comercial de Deusto et a modernis\u00e9 l&rsquo;entreprise au cours des 10 ann\u00e9es o\u00f9 il l&rsquo;a dirig\u00e9e. Apr\u00e8s la perte tr\u00e8s douloureuse d&rsquo;Eric, la famille a \u00e9t\u00e9 plong\u00e9e dans la tristesse et peu de temps apr\u00e8s, M. Ruiz Zufiaur est \u00e9galement d\u00e9c\u00e9d\u00e9.<\/p>\n<p>Jos\u00e9 Cruz Jr. a d\u00fb reprendre l&rsquo;entreprise. Bien qu&rsquo;il connaisse \u00e0 peine le produit, le secteur ou le fonctionnement d&rsquo;une entreprise industrielle, il est entr\u00e9 dans sa gestion pour pouvoir la maintenir car s&rsquo;il savait quelque chose, c&rsquo;\u00e9tait qu&rsquo;il devait prendre soin de l&rsquo;entreprise et des personnes qui y travaillaient parce que son p\u00e8re faisait partie de sa famille et qu&rsquo;il vivait ainsi depuis qu&rsquo;il \u00e9tait enfant.<\/p>\n<p>Il savait \u00e9galement que la qualit\u00e9 du produit devait \u00eatre une garantie absolue dans un secteur aussi exigeant en mati\u00e8re de s\u00e9curit\u00e9 et d&rsquo;efficacit\u00e9.<\/p>\n<p>Enfin, conscient que le personnel de l&rsquo;entreprise savait tr\u00e8s bien faire son travail, il a commenc\u00e9 \u00e0 concevoir un code d&rsquo;\u00e9thique et de conduite, bas\u00e9 sur la culture d&rsquo;entreprise que son p\u00e8re et son fr\u00e8re Eric avaient impr\u00e9gn\u00e9e des travailleurs.<\/p>\n<p>Actuellement, Jos\u00e9 Cruz Ruiz Jr. est l&rsquo;administrateur unique et Arancha Guerrero est la directrice.<\/p>\n<p>Le code de conduite est unique entre les deux. Cela repose fondamentalement sur les bonnes pratiques avec les travailleurs. Priorit\u00e9 \u00e0 la bonne communication, \u00e0 la bonne ambiance, au projet commun et \u00e0 l&rsquo;h\u00e9ritage. \u00c9vitez les conflits collectifs et maintenez toujours une relation fluide tant avec les syndicats qu&rsquo;avec chacun des travailleurs.<\/p>\n<p>Toujours, sans exception, tous les travailleurs qui en ont besoin sont soign\u00e9s, de la m\u00eame mani\u00e8re, sans cha\u00eene de commandement. Travail de gestion et d&rsquo;administration dans le magasin et dans les bureaux, m\u00eame avec des postes de travail physiques mobiles. La direction travaille main dans la main avec les soudeurs, les tourneurs, le service technico-commercial ou les ouvriers du service textile. Avec tout le monde de mani\u00e8re \u00e9gale, en maintenant une relation \u00e9troite avec l&rsquo;ensemble de l&rsquo;\u00e9quipe.<\/p>\n<p>Au sein de cette culture d&rsquo;entreprise, se trouve le concept multidisciplinaire de l&rsquo;ensemble de la main-d&rsquo;\u0153uvre.<\/p>\n<p>Nous travaillons avec des indicateurs (crit\u00e8res mesurables) pour inciter chaque ouvrier de l&rsquo;atelier \u00e0 apprendre le plus grand nombre de t\u00e2ches et ainsi \u00eatre capable d&rsquo;\u00eatre plus agile en cas d&rsquo;urgence et \u00eatre capable de g\u00e9rer les pics de travail qui accompagnent les arr\u00eats d&rsquo;usines en contrat cadre. Ces indicateurs marquent dans des tableaux les t\u00e2ches que chaque travailleur est capable de faire, ce qui doit \u00eatre am\u00e9lior\u00e9 ou quelle formation est n\u00e9cessaire. Cela a permis la cr\u00e9ation d&rsquo;un espace R+D+I exceptionnel.<\/p>\n<p>Nous avons actuellement des contrats-cadres avec Cepsa, Repsol, Sabic, Galp et Dupont. Ce portefeuille nous a fait repenser notre fa\u00e7on de g\u00e9rer l&rsquo;atelier et le d\u00e9partement technico-commercial.<\/p>\n<p>Nous avons, dans chaque zone, des tableaux avec les arr\u00eats pr\u00e9vus dans chaque raffinerie des contrats cadres. Nous essayons de maintenir un stock \u00e9lev\u00e9 de toutes les mati\u00e8res premi\u00e8res n\u00e9cessaires et nous organisons des vacances pour le personnel, en tenant toujours compte des arr\u00eats pr\u00e9vus. Notre priorit\u00e9 est d&rsquo;anticiper les besoins de nos clients afin de r\u00e9pondre \u00e0 toutes leurs demandes et urgences de derni\u00e8re minute.<\/p>\n<p>Nous sommes pleinement conscients de l&rsquo;importance de notre disponibilit\u00e9 totale et de notre flexibilit\u00e9 pour r\u00e9pondre \u00e0 toute demande in-extremis.<\/p>\n<p>Nous avons un protocole \u00e9tabli pour pouvoir fabriquer et envoyer n&rsquo;importe quel joint ou compensateur \u00e0 n&rsquo;importe quelle centrale \u00e9lectrique en Espagne et au Portugal en quelques heures.<\/p>\n<p>La relation avec les fournisseurs doit \u00e9galement \u00eatre une relation de confiance totale. Lorsque nous travaillons avec des urgences, nous avons besoin de fournisseurs de mati\u00e8res premi\u00e8res et de services qui nous offrent cette agilit\u00e9 et cette s\u00e9curit\u00e9. La seule fa\u00e7on est de travailler avec des fournisseurs r\u00e9guliers et c&rsquo;est ce que nous encourageons. La cha\u00eene d&rsquo;approvisionnement doit \u00eatre garantie, en cherchant toujours \u00e0 respecter notre politique <strong>du 0 km , <\/strong>\u00e9tant ainsi le plus responsable possible avec l&rsquo;environnement.<\/p>\n<p>Kempchen-Comdiflex pr\u00e9tend \u00eatre \u00e0 la pointe du contr\u00f4le des fuites, de la dilatation et de la corrosion dans l&rsquo;industrie p\u00e9trochimique.<\/p>\n<p>Notre service R&amp;D d\u00e9veloppe actuellement plusieurs produits pour le stockage et le transport de l&rsquo;hydrog\u00e8ne vert. Ce d\u00e9partement, \u00e0 son tour, travaille quotidiennement sur de nouveaux processus de fabrication (Lean Manufacturing) pour augmenter la productivit\u00e9 de nos ressources humaines et mat\u00e9rielles.<\/p>\n<p>Notre relation avec l&rsquo;administration publique et les entit\u00e9s financi\u00e8res est \u00e9troite et sans probl\u00e8mes. Nous n&rsquo;avons aucun d\u00e9faut, ni en tant que cr\u00e9anciers ni en tant que d\u00e9biteurs. Nous travaillons avec Cr\u00e9dito y Cauci\u00f3n pour \u00e9viter de travailler avec des clients potentiellement probl\u00e9matiques. Nos besoins de financement sp\u00e9cifiques sont couverts sans probl\u00e8me majeur.<\/p>\n<p>Ce sont les mesures que nous mettons actuellement en \u0153uvre pour \u00eatre socialement et \u00e9cologiquement responsables. Mais les crit\u00e8res ESG sont une forme de gestion, d&rsquo;am\u00e9lioration continue, c&rsquo;est pourquoi ce rapport doit \u00eatre revu et mis \u00e0 jour fr\u00e9quemment, en nous adaptant non seulement aux r\u00e9glementations environnementales de plus en plus exigeantes, mais aussi \u00e0 notre propre \u00e9thique et culture d&rsquo;entreprise, qui vise \u00eatre meilleur chaque jour. Plus solidaire, plus responsable, plus empathique et finalement, plus respectueux du monde qui nous entoure, de la culture dont nous avons h\u00e9rit\u00e9 et que nous allons l\u00e9guer aux g\u00e9n\u00e9rations futures.<\/p>\n<p style=\"text-align: right;\">5 d\u00e9cembre 2022<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1012.96px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\" style=\"font-family:&quot;Roboto&quot;;font-weight:400;transform:translate3d(0,0,0);\"><p><strong>Angel Cerrillo Granado<\/strong><br \/>\n<em>Resp. Calidad, Gesti\u00f3n Medioarnbiente y Prevenci\u00f3n de Riesgos Laborales<\/em><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:50% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 3.84%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 3.84%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-3\" style=\"font-family:&quot;Roboto&quot;;font-weight:400;transform:translate3d(0,0,0);\"><p><strong>Arancha Guerrero<\/strong><br \/>\n<em>Gerente<\/em><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:50% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 3.84%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 3.84%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":10245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85,132,129],"tags":[],"class_list":["post-10262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comdiflex","category-equipo-en-fr","category-rd-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comdiflex | CRIT\u00c8RES ESG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comdiflex.com\/fr\/criteres-esg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CRIT\u00c8RES ESG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comdiflex.com\/fr\/criteres-esg\/\" \/>\n<meta property=\"og:site_name\" content=\"Comdiflex\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-07T12:53:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-12T10:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1318\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Janbiel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/\"},\"author\":{\"name\":\"Janbiel\",\"@id\":\"https:\/\/comdiflex.com\/fr\/#\/schema\/person\/432b7f9bdea7a183dff670345f9151d2\"},\"headline\":\"CRIT\u00c8RES ESG\",\"datePublished\":\"2022-12-07T12:53:13+00:00\",\"dateModified\":\"2022-12-12T10:33:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/\"},\"wordCount\":3721,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png\",\"articleSection\":[\"Comdiflex\",\"Equipo\",\"R&amp;D\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/\",\"url\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/\",\"name\":\"Comdiflex | CRIT\u00c8RES ESG\",\"isPartOf\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png\",\"datePublished\":\"2022-12-07T12:53:13+00:00\",\"dateModified\":\"2022-12-12T10:33:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/comdiflex.com\/fr\/criteres-esg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage\",\"url\":\"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png\",\"contentUrl\":\"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png\",\"width\":1318,\"height\":628,\"caption\":\"desarrollo sostenible\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/comdiflex.com\/fr\/criteres-esg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/comdiflex.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CRIT\u00c8RES ESG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/comdiflex.com\/fr\/#website\",\"url\":\"https:\/\/comdiflex.com\/fr\/\",\"name\":\"Comdiflex\",\"description\":\"Fabricante de juntas y compensadores | Fabricaci\u00f3n urgente\",\"publisher\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/comdiflex.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/comdiflex.com\/fr\/#organization\",\"name\":\"COMDIFLEX\",\"url\":\"https:\/\/comdiflex.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/comdiflex.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/comdiflex.com\/wp-content\/uploads\/2021\/06\/logocomdiflex275x62.png\",\"contentUrl\":\"https:\/\/comdiflex.com\/wp-content\/uploads\/2021\/06\/logocomdiflex275x62.png\",\"width\":275,\"height\":62,\"caption\":\"COMDIFLEX\"},\"image\":{\"@id\":\"https:\/\/comdiflex.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/grupo-industrial-kempchen-comdiflex-s-a-\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/comdiflex.com\/fr\/#\/schema\/person\/432b7f9bdea7a183dff670345f9151d2\",\"name\":\"Janbiel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/75ae1c8296b3a09e440f68a4addd8732a3190e88b8ed51a2faaed7c2f9616fc6?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/75ae1c8296b3a09e440f68a4addd8732a3190e88b8ed51a2faaed7c2f9616fc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/75ae1c8296b3a09e440f68a4addd8732a3190e88b8ed51a2faaed7c2f9616fc6?s=96&d=mm&r=g\",\"caption\":\"Janbiel\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comdiflex | CRIT\u00c8RES ESG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comdiflex.com\/fr\/criteres-esg\/","og_locale":"fr_FR","og_type":"article","og_title":"CRIT\u00c8RES ESG","og_url":"https:\/\/comdiflex.com\/fr\/criteres-esg\/","og_site_name":"Comdiflex","article_published_time":"2022-12-07T12:53:13+00:00","article_modified_time":"2022-12-12T10:33:54+00:00","og_image":[{"width":1318,"height":628,"url":"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png","type":"image\/png"}],"author":"Janbiel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/#article","isPartOf":{"@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/"},"author":{"name":"Janbiel","@id":"https:\/\/comdiflex.com\/fr\/#\/schema\/person\/432b7f9bdea7a183dff670345f9151d2"},"headline":"CRIT\u00c8RES ESG","datePublished":"2022-12-07T12:53:13+00:00","dateModified":"2022-12-12T10:33:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/"},"wordCount":3721,"commentCount":0,"publisher":{"@id":"https:\/\/comdiflex.com\/fr\/#organization"},"image":{"@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage"},"thumbnailUrl":"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png","articleSection":["Comdiflex","Equipo","R&amp;D"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comdiflex.com\/fr\/criteres-esg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/","url":"https:\/\/comdiflex.com\/fr\/criteres-esg\/","name":"Comdiflex | CRIT\u00c8RES ESG","isPartOf":{"@id":"https:\/\/comdiflex.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage"},"image":{"@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage"},"thumbnailUrl":"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png","datePublished":"2022-12-07T12:53:13+00:00","dateModified":"2022-12-12T10:33:54+00:00","breadcrumb":{"@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comdiflex.com\/fr\/criteres-esg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/#primaryimage","url":"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png","contentUrl":"https:\/\/comdiflex.com\/wp-content\/uploads\/2022\/12\/desarrollo-sostenible.png","width":1318,"height":628,"caption":"desarrollo sostenible"},{"@type":"BreadcrumbList","@id":"https:\/\/comdiflex.com\/fr\/criteres-esg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/comdiflex.com\/fr\/"},{"@type":"ListItem","position":2,"name":"CRIT\u00c8RES ESG"}]},{"@type":"WebSite","@id":"https:\/\/comdiflex.com\/fr\/#website","url":"https:\/\/comdiflex.com\/fr\/","name":"Comdiflex","description":"Fabricante de juntas y compensadores | Fabricaci\u00f3n urgente","publisher":{"@id":"https:\/\/comdiflex.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comdiflex.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/comdiflex.com\/fr\/#organization","name":"COMDIFLEX","url":"https:\/\/comdiflex.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/comdiflex.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/comdiflex.com\/wp-content\/uploads\/2021\/06\/logocomdiflex275x62.png","contentUrl":"https:\/\/comdiflex.com\/wp-content\/uploads\/2021\/06\/logocomdiflex275x62.png","width":275,"height":62,"caption":"COMDIFLEX"},"image":{"@id":"https:\/\/comdiflex.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/grupo-industrial-kempchen-comdiflex-s-a-\/"]},{"@type":"Person","@id":"https:\/\/comdiflex.com\/fr\/#\/schema\/person\/432b7f9bdea7a183dff670345f9151d2","name":"Janbiel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/75ae1c8296b3a09e440f68a4addd8732a3190e88b8ed51a2faaed7c2f9616fc6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/75ae1c8296b3a09e440f68a4addd8732a3190e88b8ed51a2faaed7c2f9616fc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/75ae1c8296b3a09e440f68a4addd8732a3190e88b8ed51a2faaed7c2f9616fc6?s=96&d=mm&r=g","caption":"Janbiel"}}]}},"_links":{"self":[{"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/posts\/10262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/comments?post=10262"}],"version-history":[{"count":0,"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/posts\/10262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/media\/10245"}],"wp:attachment":[{"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/media?parent=10262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/categories?post=10262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comdiflex.com\/fr\/wp-json\/wp\/v2\/tags?post=10262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}